{"id":11823,"date":"2025-05-07T05:29:27","date_gmt":"2025-05-07T09:29:27","guid":{"rendered":"https:\/\/amsclinic.ca\/?p=11823"},"modified":"2026-04-05T09:33:17","modified_gmt":"2026-04-05T13:33:17","slug":"la-sciatique-expliquee","status":"publish","type":"post","link":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/","title":{"rendered":"Sciatique : comprendre, pr\u00e9venir et soulager cette douleur intense"},"content":{"rendered":"<p>La <strong>sciatique<\/strong>\u00a0est une affection qui touche un nombre surprenant d&rsquo;adultes chaque ann\u00e9e, causant des douleurs parfois d\u00e9bilitantes et limitantes. Cette pathologie d\u00e9coule souvent de probl\u00e8mes profonds au niveau de la\u00a0<strong>colonne vert\u00e9brale<\/strong>, n\u00e9cessitant une attention particuli\u00e8re pour \u00eatre g\u00e9r\u00e9e efficacement. Plongeons ensemble dans les d\u00e9tails de ces maux complexes, en examinant leurs sympt\u00f4mes, leurs causes, les traitements possibles et les mesures pr\u00e9ventives.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13397 aligncenter\" src=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image2.jpg\" alt=\"\" width=\"302\" height=\"473\" srcset=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image2.jpg 302w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image2-192x300.jpg 192w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/><\/p>\n<h2><strong>Qu&rsquo;est-ce qu&rsquo;une sciatique ?<\/strong><\/h2>\n<p>La\u00a0<strong>sciatique<\/strong>\u00a0est une douleur qui se propage le long du\u00a0<strong>nerf sciatique<\/strong>, le plus long nerf du corps humain. Ce nerf s&rsquo;\u00e9tend de la partie inf\u00e9rieure du dos, traverse les hanches et les fesses, et descend dans chaque jambe. La douleur sciatique est g\u00e9n\u00e9ralement caus\u00e9e par une compression ou une\u00a0<strong>irritation du nerf sciatique<\/strong>, souvent due \u00e0 une hernie discale, un r\u00e9tr\u00e9cissement du\u00a0<strong>canal rachidien<\/strong>\u00a0(st\u00e9nose spinale), ou une blessure.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/hGnOXNG7bYU?si=VD3UyGvgARJIXyYQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2><strong>Quels sont les sympt\u00f4mes de la sciatique ?\u00a0<\/strong><\/h2>\n<p>Les sympt\u00f4mes de la sciatique peuvent varier en intensit\u00e9 et en localisation, mais incluent g\u00e9n\u00e9ralement :<\/p>\n<ul>\n<li>Une\u00a0<strong>douleur aigu\u00eb<\/strong>\u00a0ou lancinante qui commence dans le bas du dos et descend dans la jambe.<\/li>\n<li>Une sensation de br\u00fblure ou de picotement le long du\u00a0<strong>nerf sciatique<\/strong>.<\/li>\n<\/ul>\n<p>Dans certains cas graves, des sympt\u00f4mes suppl\u00e9mentaires tels que des engourdissements, une\u00a0<strong>faiblesse musculaire<\/strong>, une perte de sensation dans certaines parties de la jambe ou m\u00eame des alt\u00e9rations du contr\u00f4le de l&rsquo;intestin ou de la vessie peuvent survenir.<\/p>\n<h2><strong>Les causes sous-jacentes de la douleur sciatique<\/strong><\/h2>\n<p>Plusieurs facteurs peuvent mener \u00e0 une pression excessive exerc\u00e9e sur le\u00a0<strong>nerf sciatique<\/strong>. La cause la plus commune demeure l&rsquo;<strong>hernie discale<\/strong>, o\u00f9 l&rsquo;irritation d&rsquo;un\u00a0<strong>disque intervert\u00e9bral<\/strong>\u00a0exerce une pression sur le nerf. Toutefois, ce n&rsquo;est pas la seule condition impliqu\u00e9e.<\/p>\n<p>Outre l&rsquo;hernie discale, l&rsquo;arthrose, les tumeurs vert\u00e9brales, les fractures et diverses infections peuvent \u00e9galement comprimer le nerf sciatique. Le nerf sciatique pourrait aussi \u00e8tre comprim\u00e9 au niveau du fessier. Chez environ 15% de la population (https:\/\/novusspinecenter.com), le nerf sciatique passe \u00e0 travers le muscle du piramidal. Un spasme pathologique du piramidale va donc reproduire les m\u00eames sympt\u00f4mes qu\u2019une sciatique. Chacune de ces affections peut inflammer ou bloquer le passage naturel du nerf \u00e0 travers la colonne, intensifiant ainsi la douleur. De plus, des facteurs de risque tels qu&rsquo;une mauvaise posture, l&rsquo;<strong>ob\u00e9sit\u00e9<\/strong>, et des chutes accidentelles amplifient les possibilit\u00e9s de d\u00e9velopper une sciatique.<\/p>\n<h2><strong>La sciatique chez la femme enceinte\u00a0<\/strong><\/h2>\n<p>Chez les femmes enceintes, la\u00a0<strong>sciatique<\/strong>\u00a0peut appara\u00eetre en raison de changements corporels importants. L&rsquo;expansion de l&rsquo;ut\u00e9rus ou le changement du centre de gravit\u00e9 peut causer une accentuation de la\u00a0<strong>courbure lombaire (lordose)<\/strong>, augmentant ainsi la pression exerc\u00e9e sur le nerf sciatique. Heureusement, cette manifestation est g\u00e9n\u00e9ralement temporaire et s&rsquo;att\u00e9nue post-accouchement.<\/p>\n<h2><strong>Comment poser le diagnostic d\u2019une sciatique ?\u00a0<\/strong><\/h2>\n<p>Le diagnostic de la sciatique commence g\u00e9n\u00e9ralement par un examen clinique approfondi. Le m\u00e9decin ou le physioth\u00e9rapeute peut demander au patient de d\u00e9crire ses sympt\u00f4mes et de r\u00e9aliser certains mouvements pour \u00e9valuer la douleur et la mobilit\u00e9 et passer des tests physique sp\u00e9cifiques \u00e0 la sciatique.<\/p>\n<p>Des\u00a0<strong>examens d&rsquo;imagerie<\/strong>, tels que des radiographies, une IRM ou un scanner, peuvent \u00eatre n\u00e9cessaires pour identifier la cause sous-jacente, comme une\u00a0<strong>hernie discale<\/strong>\u00a0ou une\u00a0<strong>st\u00e9nose spinale<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13401 aligncenter\" src=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image1.jpg\" alt=\"\" width=\"182\" height=\"277\" \/><\/p>\n<p style=\"text-align: center;\">Titre\u00a0: IRM avec une double hernie discale<\/p>\n<h2><strong>Combien de temps peut-on souffrir d\u2019une sciatique ?\u00a0<\/strong><\/h2>\n<p>La dur\u00e9e de la sciatique peut varier consid\u00e9rablement. Dans de nombreux cas, la douleur s&rsquo;am\u00e9liore en quelques semaines avec des soins appropri\u00e9s. Cependant, si la cause sous-jacente n&rsquo;est pas trait\u00e9e, la\u00a0<strong>sciatique<\/strong>\u00a0peut devenir chronique et n\u00e9cessiter une gestion \u00e0 long terme.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13399 aligncenter\" src=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image3.jpg\" alt=\"\" width=\"1333\" height=\"2000\" srcset=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image3.jpg 1333w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image3-1280x1920.jpg 1280w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image3-980x1470.jpg 980w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/image3-480x720.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1333px, 100vw\" \/><\/p>\n<h2><strong>Les traitements pour le nerf sciatique<\/strong><\/h2>\n<ul>\n<li><a href=\"https:\/\/amsclinic.ca\/fr\/physiotherapie\/\"><strong><u>Physioth\u00e9rapie<\/u><\/strong><\/a>: des exercices sp\u00e9cifiques vont aider \u00e0 diminuer ou \u00e0 \u00e9liminer la compression sur le nerf sciatique. Une fois le nerf lib\u00e9r\u00e9, des exercices de renforcement des muscles du dos et de l\u2019\u00e9ducation et des exercices posturaux.<\/li>\n<li><strong>M\u00e9dicaments<\/strong>\u00a0: des anti-inflammatoires, des relaxants musculaires ou des injections de corticost\u00e9ro\u00efdes peuvent \u00eatre prescrits.<\/li>\n<li><strong>Chirurgie<\/strong>\u00a0: dans les cas graves, une intervention chirurgicale peut \u00eatre n\u00e9cessaire pour soulager la pression sur le nerf sciatique.<\/li>\n<li><strong>Th\u00e9rapies alternatives<\/strong>\u00a0: l<a href=\"https:\/\/amsclinic.ca\/fr\/acupuncture\/\"><u>&lsquo;acupuncture<\/u><\/a>, l\u2019<a href=\"https:\/\/amsclinic.ca\/fr\/osteopathie\/\"><u>ost\u00e9pathie<\/u><\/a>\u00a0ou la\u00a0<a href=\"https:\/\/amsclinic.ca\/fr\/approche-posturale-en-physiotherapie\/\"><u>gymnastique holistique<\/u><\/a>\u00a0peuvent \u00e9galement offrir un soulagement pour certains patients.<\/li>\n<\/ul>\n<h2><strong>Comment soulager la sciatique ?\u00a0<\/strong><\/h2>\n<p>Pour soulager la douleur, une premi\u00e8re approche repose souvent sur l&rsquo;administration de\u00a0<strong>m\u00e9dicaments antalgiques<\/strong>, telles que les anti-inflammatoires non st\u00e9ro\u00efdiens (AINS). Cependant, pour les formes de sciatique plus s\u00e9v\u00e8res, des analg\u00e9siques plus puissants, voire \u00e0 base de morphine, peuvent \u00eatre n\u00e9cessaires.<\/p>\n<p>Outre les m\u00e9dicaments, la\u00a0<strong>physioth\u00e9rapie<\/strong>\u00a0offre une multitude de strat\u00e9gies pour am\u00e9liorer la mobilit\u00e9 et r\u00e9duire progressivement la douleur. Par exemple, un physioth\u00e9rapeute peut recommander des\u00a0<strong>exercices cibl\u00e9s<\/strong>\u00a0visant \u00e0 lib\u00e9rer le nerf sciatique de sa compression et ensuite de renforcer la colonne vert\u00e9brale (la M\u00e9thode McKenzie).<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/kjRU0MHL8xU?si=0RJWwW0fOWXsk7Fc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>NOTE: vid\u00e9os en fran\u00e7ais sur lesquelles vous pouvez activer les sous-titres en anglais<\/p>\n<p>Dans les cas extr\u00eames, une intervention chirurgicale peut \u00eatre envisag\u00e9e. L&rsquo;IRM ou le scanner sont alors cruciaux pour \u00e9valuer pr\u00e9cis\u00e9ment l&#8217;emplacement et la gravit\u00e9 de l&rsquo;atteinte. Les proc\u00e9dures chirurgicales visent principalement \u00e0 supprimer ou rectifier la partie probl\u00e9matique exer\u00e7ant une pression sur le nerf sciatique.<\/p>\n<p>Voici quelques astuces pour soulager la douleur :<\/p>\n<ul>\n<li>Appliquer des compresses chaudes ou froides sur la zone douloureuse.<\/li>\n<li>Pratiquer des\u00a0<strong>exercices d&rsquo;\u00e9tirement doux<\/strong>\u00a0pour am\u00e9liorer la flexibilit\u00e9 et r\u00e9duire la pression sur le nerf sciatique.<\/li>\n<\/ul>\n<p>VIDEO ici: <a href=\"https:\/\/youtu.be\/kjRU0MHL8xU?si=N1c5sVnHTHp6CMgm\"><u>https:\/\/youtu.be\/kjRU0MHL8xU?si=N1c5sVnHTHp6CMgm<\/u><\/a><\/p>\n<ul>\n<li>Prendre des analg\u00e9siques en vente libre, comme l&rsquo;ibuprof\u00e8ne ou le parac\u00e9tamol.<\/li>\n<li>\u00c9viter de rester assis ou debout pendant de longues p\u00e9riodes.<\/li>\n<\/ul>\n<h2><strong>Comment pr\u00e9venir l&rsquo;apparition de la sciatique ?\u00a0<\/strong><\/h2>\n<p>Bien que tous les cas ne soient pas \u00e9vitables, certaines habitudes peuvent aider \u00e0 r\u00e9duire le risque de d\u00e9velopper une sciatique. Tout d&rsquo;abord, maintenir une bonne\u00a0<strong>posture<\/strong>\u00a0au quotidien joue un r\u00f4le cl\u00e9 dans la pr\u00e9vention des tensions ind\u00e9sirables sur la colonne vert\u00e9brale. Voici quelques conseils pratiques :<\/p>\n<ul>\n<li>Pratiquer r\u00e9guli\u00e8rement des exercices d&rsquo;<strong>\u00e9tirement<\/strong>\u00a0et de renforcement, tel que prescrit par votre physioth\u00e9rapeute, pour soutenir la structure du dos.<\/li>\n<li>Adopter des\u00a0<strong>\u00e9quipements ergonomiques<\/strong>\u00a0adapt\u00e9s pour le travail, notamment si vous passez de longues heures assis.<\/li>\n<li>\u00c9viter de soulever des objets lourds inappropri\u00e9s ou sans assistance.<\/li>\n<li>Maintenir un\u00a0<strong>poids sain<\/strong>\u00a0pour att\u00e9nuer la tension suppl\u00e9mentaire sur la colonne.<\/li>\n<\/ul>\n<h2><strong>L&rsquo;importance de consulter un sp\u00e9cialiste<\/strong><\/h2>\n<p>Il est imp\u00e9ratif de ne pas ignorer les premiers signes de\u00a0<strong>sciatique<\/strong>, car la pr\u00e9cocit\u00e9 du traitement influencera fortement le r\u00e9tablissement.\u00a0<strong>Consulter un physioth\u00e9rapeute<\/strong>\u00a0d\u00e8s le d\u00e9but des sympt\u00f4mes permet une investigation rapide et pr\u00e9cise de la cause profonde, r\u00e9duisant ainsi la probabilit\u00e9 de complications futures.<\/p>\n<p>Un\u00a0<strong>diagnostic<\/strong>\u00a0appropri\u00e9 reposera souvent sur un examen clinique combin\u00e9 \u00e0 des tests sp\u00e9cifique et possiblement d&rsquo;imagerie m\u00e9dicale. Ces outils aident \u00e0 confirmer la source exacte de la douleur et permettent l&rsquo;\u00e9laboration d&rsquo;un plan de traitement personnalis\u00e9. Par cons\u00e9quent, solliciter un m\u00e9decin ou un\u00a0<a href=\"https:\/\/amsclinic.ca\/fr\/therapeutes\/physiotherapie\/\"><strong><u>physioth\u00e9rapeute<\/u><\/strong><\/a>\u00a0constitue une \u00e9tape essentielle dans la gestion proactive de la sciatique.<\/p>\n<h2><strong>Quelles sont les diff\u00e9rences entre la sciatique et le syndrome du piriforme ?\u00a0<\/strong><\/h2>\n<p>La\u00a0<strong>sciatique<\/strong>\u00a0et le\u00a0<strong>syndrome du piriforme<\/strong>\u00a0partagent des sympt\u00f4mes similaires, comme des douleurs irradiantes dans la jambe, mais elles diff\u00e8rent par leur origine, leurs caract\u00e9ristiques et leur traitement.<\/p>\n<p>Contrairement \u00e0 la sciatique, le syndrome du piriforme n&rsquo;est pas li\u00e9 \u00e0 un probl\u00e8me de la colonne vert\u00e9brale. La douleur provient de la\u00a0<strong>compression du nerf sciatique<\/strong>\u00a0par le\u00a0<strong>muscle piriforme<\/strong>, situ\u00e9 dans la fesse.<\/p>\n<p>Ainsi la douleur est localis\u00e9e dans la fesse et peut irradier vers l&rsquo;arri\u00e8re de la cuisse, mais elle descend rarement jusqu&rsquo;au pied comme pour la sciatique. Le s<em>yndrome du piriforme est g\u00e9n\u00e9ralement <\/em>caus\u00e9 par une surutilisation ou\u00a0<strong>un traumatisme du muscle piriforme<\/strong>, par exemple, apr\u00e8s une activit\u00e9 physique intense ou une mauvaise posture.<\/p>\n<p>En r\u00e9sum\u00e9, la sciatique est li\u00e9e \u00e0 un probl\u00e8me nerveux d&rsquo;origine vert\u00e9brale, tandis que le syndrome du piriforme est une compression musculaire du nerf sciatique. Une consultation en physioth\u00e9rapie est essentiel pour adapter le traitement.<\/p>\n<p>Conclusion : La sciatique peut \u00eatre tr\u00e8s douloureuse et invalidante, mais avec un diagnostic pr\u00e9cis et un traitement appropri\u00e9, il est possible de g\u00e9rer les sympt\u00f4mes et d&rsquo;am\u00e9liorer la qualit\u00e9 de vie. Si vous souffrez de douleurs sciatiques, consultez\u00a0<a href=\"https:\/\/amsclinic.ca\/fr\/physiotherapie\/\"><u>notre service de physioth\u00e9rapie<\/u><\/a>\u00a0pour d\u00e9terminer la meilleure approche pour votre situation.<\/p>\n<p>R\u00e9f\u00e9rences<\/p>\n<ul class=\"reference_list\">\n<li>David Davis; Kushagra Maini; Muhammad Taqi; Arvind Vasudevan. National Library of Medicine, https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK507908\/<\/li>\n<li>Jean-Pierre Valat MD, PhD a, St\u00e9phane Genevay MD b, Marc Marty MD c, Sylvie Rozenberg MD d, Bart Koes PhD, Sciatica, Best Practice &amp; Research Clinical Rheumatology, Volume 24, Issue 2, April 2010, Pages 241-252<\/li>\n<li>Konstantinou, Kika PhD; Dunn, Kate M. PhD, Sciatica, Review of Epidemiological Studies and Prevalence Estimates, <i>Spine<\/i> 33(22):p 2464-2472, October 15, 2008.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La sciatique\u00a0est une affection qui touche un nombre surprenant d&rsquo;adultes chaque ann\u00e9e, causant des douleurs parfois d\u00e9bilitantes et limitantes. Cette pathologie d\u00e9coule souvent de probl\u00e8mes profonds au niveau de la\u00a0colonne vert\u00e9brale, n\u00e9cessitant une attention particuli\u00e8re pour \u00eatre g\u00e9r\u00e9e efficacement. Plongeons ensemble dans les d\u00e9tails de ces maux complexes, en examinant leurs sympt\u00f4mes, leurs causes, les [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":11818,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[12],"tags":[34],"ppma_author":[80],"class_list":["post-11823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-sciatique","author-rich-mo-physio-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La sciatique expliqu\u00e9e<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez tout sur la sciatique : ses causes, sympt\u00f4mes, diagnostic, dur\u00e9e, m\u00e9thodes pour soulager la douleur et les traitements disponibles pour retrouver votre confort au quotidien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sciatique expliqu\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Dans le blog, nous allons nous plonger dans le sujet fascinant et douloureux de la sciatique. Nous allons explorer l&#039;anatomie, les causes...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/\" \/>\n<meta property=\"og:site_name\" content=\"AMS Clinic\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T09:29:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T13:33:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1878\" \/>\n\t<meta property=\"og:image:height\" content=\"1253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rich &amp; Mo Physio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La sciatique expliqu\u00e9e\" \/>\n<meta name=\"twitter:description\" content=\"Dans le blog, nous allons nous plonger dans le sujet fascinant et douloureux de la sciatique. Nous allons explorer l&#039;anatomie, les causes...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rich &amp; Mo Physio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/\"},\"author\":{\"name\":\"Rich &amp; Mo Physio\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\"},\"headline\":\"Sciatique : comprendre, pr\u00e9venir et soulager cette douleur intense\",\"datePublished\":\"2025-05-07T09:29:27+00:00\",\"dateModified\":\"2026-04-05T13:33:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/\"},\"wordCount\":1575,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sciatica-explained.jpg\",\"keywords\":[\"sciatique\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/\",\"name\":\"La sciatique expliqu\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sciatica-explained.jpg\",\"datePublished\":\"2025-05-07T09:29:27+00:00\",\"dateModified\":\"2026-04-05T13:33:17+00:00\",\"description\":\"D\u00e9couvrez tout sur la sciatique : ses causes, sympt\u00f4mes, diagnostic, dur\u00e9e, m\u00e9thodes pour soulager la douleur et les traitements disponibles pour retrouver votre confort au quotidien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sciatica-explained.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sciatica-explained.jpg\",\"width\":1878,\"height\":1253,\"caption\":\"Sciatica explained\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/la-sciatique-expliquee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sciatique : comprendre, pr\u00e9venir et soulager cette douleur intense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"name\":\"AMS Clinic\",\"description\":\"Montreal Rehabilitation and Physiotherapy Clinic\",\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\",\"name\":\"AMS Clinic\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"width\":280,\"height\":100,\"caption\":\"AMS Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\",\"name\":\"Rich &amp; Mo Physio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"caption\":\"Rich &amp; Mo Physio\"},\"description\":\"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/author\\\/rich-mo-physio-1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La sciatique expliqu\u00e9e","description":"D\u00e9couvrez tout sur la sciatique : ses causes, sympt\u00f4mes, diagnostic, dur\u00e9e, m\u00e9thodes pour soulager la douleur et les traitements disponibles pour retrouver votre confort au quotidien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/","og_locale":"fr_CA","og_type":"article","og_title":"La sciatique expliqu\u00e9e","og_description":"Dans le blog, nous allons nous plonger dans le sujet fascinant et douloureux de la sciatique. Nous allons explorer l'anatomie, les causes...","og_url":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/","og_site_name":"AMS Clinic","article_published_time":"2025-05-07T09:29:27+00:00","article_modified_time":"2026-04-05T13:33:17+00:00","og_image":[{"width":1878,"height":1253,"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg","type":"image\/jpeg"}],"author":"Rich &amp; Mo Physio","twitter_card":"summary_large_image","twitter_title":"La sciatique expliqu\u00e9e","twitter_description":"Dans le blog, nous allons nous plonger dans le sujet fascinant et douloureux de la sciatique. Nous allons explorer l'anatomie, les causes...","twitter_image":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg","twitter_misc":{"\u00c9crit par":"Rich &amp; Mo Physio","Estimation du temps de lecture":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#article","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/"},"author":{"name":"Rich &amp; Mo Physio","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1"},"headline":"Sciatique : comprendre, pr\u00e9venir et soulager cette douleur intense","datePublished":"2025-05-07T09:29:27+00:00","dateModified":"2026-04-05T13:33:17+00:00","mainEntityOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/"},"wordCount":1575,"commentCount":4,"publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg","keywords":["sciatique"],"articleSection":["Blog"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/","url":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/","name":"La sciatique expliqu\u00e9e","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#primaryimage"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg","datePublished":"2025-05-07T09:29:27+00:00","dateModified":"2026-04-05T13:33:17+00:00","description":"D\u00e9couvrez tout sur la sciatique : ses causes, sympt\u00f4mes, diagnostic, dur\u00e9e, m\u00e9thodes pour soulager la douleur et les traitements disponibles pour retrouver votre confort au quotidien.","breadcrumb":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#primaryimage","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2023\/02\/Sciatica-explained.jpg","width":1878,"height":1253,"caption":"Sciatica explained"},{"@type":"BreadcrumbList","@id":"https:\/\/amsclinic.ca\/fr\/blog\/la-sciatique-expliquee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amsclinic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Sciatique : comprendre, pr\u00e9venir et soulager cette douleur intense"}]},{"@type":"WebSite","@id":"https:\/\/amsclinic.ca\/fr\/#website","url":"https:\/\/amsclinic.ca\/fr\/","name":"AMS Clinic","description":"Montreal Rehabilitation and Physiotherapy Clinic","publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amsclinic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/amsclinic.ca\/fr\/#organization","name":"AMS Clinic","url":"https:\/\/amsclinic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","width":280,"height":100,"caption":"AMS Clinic"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1","name":"Rich &amp; Mo Physio","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","caption":"Rich &amp; Mo Physio"},"description":"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.","url":"https:\/\/amsclinic.ca\/fr\/author\/rich-mo-physio-1\/"}]}},"authors":[{"term_id":80,"user_id":33,"is_guest":0,"slug":"rich-mo-physio-1","display_name":"Rich &amp; Mo Physio","avatar_url":{"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","url2x":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":""}],"_links":{"self":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/11823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/comments?post=11823"}],"version-history":[{"count":3,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/11823\/revisions"}],"predecessor-version":[{"id":13706,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/11823\/revisions\/13706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media\/11818"}],"wp:attachment":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media?parent=11823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/categories?post=11823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/tags?post=11823"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/ppma_author?post=11823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}