{"id":12126,"date":"2023-10-06T12:17:41","date_gmt":"2023-10-06T16:17:41","guid":{"rendered":"https:\/\/amsclinic.ca\/?p=12126"},"modified":"2026-04-05T09:35:57","modified_gmt":"2026-04-05T13:35:57","slug":"comment-perdre-du-poid-exercise-ou-diete","status":"publish","type":"post","link":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/","title":{"rendered":"Comment perdre du poids: Exercice ou di\u00e8te?"},"content":{"rendered":"<p>J\u2019aimerais passer en revue les r\u00e9sultats d\u2019une recherche r\u00e9cente que j\u2019ai lue. L&rsquo;\u00e9tude compare l&rsquo;<a href=\"https:\/\/amsclinic.ca\/fr\/blog\/les-avantages-de-lactivite-physique\/\" target=\"_blank\" rel=\"noopener\">impact de l&rsquo;exercice<\/a> et de la r\u00e9duction de l&rsquo;apport calorique sur la perte de graisse.<\/p>\n<h2>Comparer l&rsquo;exercice et l&rsquo;apport calorique<\/h2>\n<p>Dans cette \u00e9tude, les chercheurs ont examin\u00e9 l\u2019efficacit\u00e9 de l\u2019exercice et de la restriction calorique pour r\u00e9duire la graisse visc\u00e9rale, qui peut \u00eatre nocive en cas d\u2019exc\u00e8s. L&rsquo;ob\u00e9sit\u00e9 est une pr\u00e9occupation mondiale et les professionnels de la sant\u00e9 recommandent souvent des changements de mode de vie, tels que l&rsquo;exercice et la r\u00e9duction des calories, pour y rem\u00e9dier.<\/p>\n<h2>M\u00e9thodologie de recherche<\/h2>\n<p>Les auteurs de l\u2019\u00e9tude ont examin\u00e9 40 articles de recherche diff\u00e9rents, portant sur un total de 2 190 participants. Ils ont utilis\u00e9 des analyses sp\u00e9cialis\u00e9es pour mesurer la graisse visc\u00e9rale autour des organes des individus. De plus, ils ont veill\u00e9 \u00e0 ce que l\u2019exercice et la r\u00e9duction de l\u2019apport calorique entra\u00eenent une perte de poids hebdomadaire \u00e9quivalente.<\/p>\n<h2>Principales conclusions<\/h2>\n<h3>L\u2019\u00e9tude a donn\u00e9 des r\u00e9sultats importants\u00a0:<\/h3>\n<p>L\u2019exercice et la restriction calorique peuvent tous deux r\u00e9duire efficacement la graisse visc\u00e9rale nocive, l\u2019exercice montrant une corr\u00e9lation positive\u00a0: plus d\u2019exercice entra\u00eene une plus grande perte de graisse.<br \/>\nCependant, augmenter le degr\u00e9 de restriction calorique n\u2019a pas n\u00e9cessairement am\u00e9lior\u00e9 la perte de graisse.<\/p>\n<h3>Cons\u00e9quences<\/h3>\n<p>Alors, que peut-on conclure ?<\/p>\n<p>L\u2019exercice semble \u00eatre une m\u00e9thode plus efficace pour r\u00e9duire la graisse visc\u00e9rale nocive que la simple r\u00e9duction de l\u2019apport calorique.<br \/>\nUne r\u00e9duction extr\u00eame des calories peut entra\u00eener une perte musculaire et un ralentissement du m\u00e9tabolisme, ce qui rend la perte de poids plus difficile.<br \/>\nL\u2019exercice physique permet de perdre de la graisse tout en pr\u00e9servant la masse musculaire, ce qui est b\u00e9n\u00e9fique pour la sant\u00e9 \u00e0 long terme.<\/p>\n<h2>En conclusion<\/h2>\n<p>En r\u00e9sum\u00e9, il est conseill\u00e9 de se concentrer sur l\u2019exercice ou de la physioth\u00e9rapie sportive pour ceux qui cherchent \u00e0 r\u00e9duire la graisse visc\u00e9rale dangereuse autour de leurs organes. N\u00e9anmoins, des recherches suppl\u00e9mentaires sont n\u00e9cessaires pour comprendre de mani\u00e8re globale les effets de la r\u00e9duction des calories sur ce type de graisse.<\/p>\n<h2>Auteur et r\u00e9f\u00e9rences<\/h2>\n<p>Les auteurs de l&rsquo;\u00e9tude originale sont\u00a0: Francesco Recchia, Chit K Leung, Angus P Yu, Welton Leung, Danny J Yu, Daniel Y Fong, David Montero, Chi-Ho Lee, Stephan HS Wong et Parco M Siu.<\/p>\n<h2>L\u2019\u00e9tude a fait r\u00e9f\u00e9rence aux sources suivantes\u00a0:<\/h2>\n<ol>\n<li>Organisation Mondiale de la Sant\u00e9. Ob\u00e9sit\u00e9 et surpoids [Fiche d&rsquo;information] 2021.<\/li>\n<li>Despr\u00e9s JP, Cartier A, C\u00f4t\u00e9 M, et al. Le concept de risque cardiom\u00e9tabolique : relier les domaines de la diab\u00e9tologie et de la cardiologie. Ann Med 2008;40(7):514-23.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019aimerais passer en revue les r\u00e9sultats d\u2019une recherche r\u00e9cente que j\u2019ai lue. L&rsquo;\u00e9tude compare l&rsquo;impact de l&rsquo;exercice et de la r\u00e9duction de l&rsquo;apport calorique sur la perte de graisse. Comparer l&rsquo;exercice et l&rsquo;apport calorique Dans cette \u00e9tude, les chercheurs ont examin\u00e9 l\u2019efficacit\u00e9 de l\u2019exercice et de la restriction calorique pour r\u00e9duire la graisse visc\u00e9rale, qui [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":6243,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[12],"tags":[],"ppma_author":[80],"class_list":["post-12126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","author-rich-mo-physio-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment perdre du poids: Exercice ou di\u00e8te? - AMS Clinic<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les r\u00e9sultats d&#039;une \u00e9tude comparative sur la perte de graisse par l&#039;exercice versus par la r\u00e9duction calorique. L&#039;impact sur la graisse visc\u00e9rale est analys\u00e9, avec des conseils pour une meilleure sant\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment perdre du poids: Exercice ou di\u00e8te? - AMS Clinic\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les r\u00e9sultats d&#039;une \u00e9tude comparative sur la perte de graisse par l&#039;exercice versus par la r\u00e9duction calorique. L&#039;impact sur la graisse visc\u00e9rale est analys\u00e9, avec des conseils pour une meilleure sant\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/\" \/>\n<meta property=\"og:site_name\" content=\"AMS Clinic\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-06T16:17:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T13:35:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-therapists-doctors.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rich &amp; Mo Physio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rich &amp; Mo Physio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/\"},\"author\":{\"name\":\"Rich &amp; Mo Physio\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\"},\"headline\":\"Comment perdre du poids: Exercice ou di\u00e8te?\",\"datePublished\":\"2023-10-06T16:17:41+00:00\",\"dateModified\":\"2026-04-05T13:35:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/\"},\"wordCount\":493,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/physio-therapists-doctors.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/\",\"name\":\"Comment perdre du poids: Exercice ou di\u00e8te? - AMS Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/physio-therapists-doctors.jpg\",\"datePublished\":\"2023-10-06T16:17:41+00:00\",\"dateModified\":\"2026-04-05T13:35:57+00:00\",\"description\":\"D\u00e9couvrez les r\u00e9sultats d'une \u00e9tude comparative sur la perte de graisse par l'exercice versus par la r\u00e9duction calorique. L'impact sur la graisse visc\u00e9rale est analys\u00e9, avec des conseils pour une meilleure sant\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/physio-therapists-doctors.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/physio-therapists-doctors.jpg\",\"width\":350,\"height\":450,\"caption\":\"physiotherapy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/comment-perdre-du-poid-exercise-ou-diete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment perdre du poids: Exercice ou di\u00e8te?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"name\":\"AMS Clinic\",\"description\":\"Montreal Rehabilitation and Physiotherapy Clinic\",\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\",\"name\":\"AMS Clinic\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"width\":280,\"height\":100,\"caption\":\"AMS Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\",\"name\":\"Rich &amp; Mo Physio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"caption\":\"Rich &amp; Mo Physio\"},\"description\":\"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/author\\\/rich-mo-physio-1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment perdre du poids: Exercice ou di\u00e8te? - AMS Clinic","description":"D\u00e9couvrez les r\u00e9sultats d'une \u00e9tude comparative sur la perte de graisse par l'exercice versus par la r\u00e9duction calorique. L'impact sur la graisse visc\u00e9rale est analys\u00e9, avec des conseils pour une meilleure sant\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/","og_locale":"fr_CA","og_type":"article","og_title":"Comment perdre du poids: Exercice ou di\u00e8te? - AMS Clinic","og_description":"D\u00e9couvrez les r\u00e9sultats d'une \u00e9tude comparative sur la perte de graisse par l'exercice versus par la r\u00e9duction calorique. L'impact sur la graisse visc\u00e9rale est analys\u00e9, avec des conseils pour une meilleure sant\u00e9.","og_url":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/","og_site_name":"AMS Clinic","article_published_time":"2023-10-06T16:17:41+00:00","article_modified_time":"2026-04-05T13:35:57+00:00","og_image":[{"width":350,"height":450,"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-therapists-doctors.jpg","type":"image\/jpeg"}],"author":"Rich &amp; Mo Physio","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rich &amp; Mo Physio","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#article","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/"},"author":{"name":"Rich &amp; Mo Physio","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1"},"headline":"Comment perdre du poids: Exercice ou di\u00e8te?","datePublished":"2023-10-06T16:17:41+00:00","dateModified":"2026-04-05T13:35:57+00:00","mainEntityOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/"},"wordCount":493,"commentCount":0,"publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-therapists-doctors.jpg","articleSection":["Blog"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/","url":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/","name":"Comment perdre du poids: Exercice ou di\u00e8te? - AMS Clinic","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#primaryimage"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-therapists-doctors.jpg","datePublished":"2023-10-06T16:17:41+00:00","dateModified":"2026-04-05T13:35:57+00:00","description":"D\u00e9couvrez les r\u00e9sultats d'une \u00e9tude comparative sur la perte de graisse par l'exercice versus par la r\u00e9duction calorique. L'impact sur la graisse visc\u00e9rale est analys\u00e9, avec des conseils pour une meilleure sant\u00e9.","breadcrumb":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#primaryimage","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-therapists-doctors.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-therapists-doctors.jpg","width":350,"height":450,"caption":"physiotherapy"},{"@type":"BreadcrumbList","@id":"https:\/\/amsclinic.ca\/fr\/blog\/comment-perdre-du-poid-exercise-ou-diete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amsclinic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment perdre du poids: Exercice ou di\u00e8te?"}]},{"@type":"WebSite","@id":"https:\/\/amsclinic.ca\/fr\/#website","url":"https:\/\/amsclinic.ca\/fr\/","name":"AMS Clinic","description":"Montreal Rehabilitation and Physiotherapy Clinic","publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amsclinic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/amsclinic.ca\/fr\/#organization","name":"AMS Clinic","url":"https:\/\/amsclinic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","width":280,"height":100,"caption":"AMS Clinic"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1","name":"Rich &amp; Mo Physio","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","caption":"Rich &amp; Mo Physio"},"description":"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.","url":"https:\/\/amsclinic.ca\/fr\/author\/rich-mo-physio-1\/"}]}},"authors":[{"term_id":80,"user_id":33,"is_guest":0,"slug":"rich-mo-physio-1","display_name":"Rich &amp; Mo Physio","avatar_url":{"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","url2x":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":""}],"_links":{"self":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/12126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/comments?post=12126"}],"version-history":[{"count":1,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/12126\/revisions"}],"predecessor-version":[{"id":19726,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/12126\/revisions\/19726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media\/6243"}],"wp:attachment":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media?parent=12126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/categories?post=12126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/tags?post=12126"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/ppma_author?post=12126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}