{"id":12183,"date":"2017-03-29T18:48:00","date_gmt":"2017-03-29T22:48:00","guid":{"rendered":"https:\/\/amsclinic.ca\/?p=12183"},"modified":"2026-04-05T09:56:34","modified_gmt":"2026-04-05T13:56:34","slug":"traumatismes-craniens-et-cervicaux-dans-le-sport","status":"publish","type":"post","link":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/","title":{"rendered":"Traumatismes cr\u00e2niens et cervicaux dans le sport"},"content":{"rendered":"<p>McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport. Ils ont examin\u00e9 divers sports, notamment le rugby, le hockey sur glace, le football am\u00e9ricain, le baseball, le soccer, la boxe, le cricket, les courses hippiques, le ski et le snowboard.<\/p>\n<p>Un des facteurs majeurs pouvant aider \u00e0 pr\u00e9venir les blessures \u00e0 la t\u00eate est la duret\u00e9 d&rsquo;une surface. Ils citent une \u00e9tude de Marshal et al, 2003, montrant qu&rsquo;en utilisant des mat\u00e9riaux plus l\u00e9gers et moins denses pour une balle de baseball, le taux de blessures a diminu\u00e9 de 28%. La nature du terrain joue \u00e9galement un r\u00f4le. Naunheim et al, 2002 ont rapport\u00e9 que des terrains plus souples en football australien entra\u00eenent moins de commotions c\u00e9r\u00e9brales. Ils poursuivent avec les revues de Thompson et al, 1999 et Levy et al, 2004, indiquant que les casques peuvent r\u00e9duire les taux de commotion de 74% et les d\u00e9c\u00e8s de 84% lorsqu&rsquo;ils sont utilis\u00e9s de mani\u00e8re g\u00e9n\u00e9ralis\u00e9e dans un sport comme le cyclisme ou le football. Les casques de ski ont \u00e9galement \u00e9t\u00e9 montr\u00e9s pour r\u00e9duire les blessures de 56%.<\/p>\n<p>\u00c0 l&rsquo;heure actuelle, il est s\u00fbr de dire que les casques devraient g\u00e9n\u00e9ralement \u00eatre port\u00e9s chaque fois que possible et que les mat\u00e9riaux devraient \u00eatre con\u00e7us de mani\u00e8re \u00e0 minimiser le risque de l\u00e9sion c\u00e9r\u00e9brale traumatique pour les joueurs et le public. Comme nous l&rsquo;avons vu dans notre s\u00e9rie sur les commotions c\u00e9r\u00e9brales et les blessures au cou, ces blessures surviennent beaucoup trop fr\u00e9quemment et peuvent avoir des cons\u00e9quences qui changent la vie d&rsquo;un joueur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport. Ils ont examin\u00e9 divers sports, notamment le rugby, le hockey sur glace, le football am\u00e9ricain, le baseball, le soccer, la boxe, le cricket, les courses hippiques, [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":6455,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[12],"tags":[],"ppma_author":[80],"class_list":["post-12183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","author-rich-mo-physio-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traumatismes cr\u00e2niens et cervicaux dans le sport - AMS Clinic<\/title>\n<meta name=\"description\" content=\"McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traumatismes cr\u00e2niens et cervicaux dans le sport - AMS Clinic\" \/>\n<meta property=\"og:description\" content=\"McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"AMS Clinic\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-29T22:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T13:56:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/03\/head-injury-sport.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rich &amp; Mo Physio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rich &amp; Mo Physio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/\"},\"author\":{\"name\":\"Rich &amp; Mo Physio\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\"},\"headline\":\"Traumatismes cr\u00e2niens et cervicaux dans le sport\",\"datePublished\":\"2017-03-29T22:48:00+00:00\",\"dateModified\":\"2026-04-05T13:56:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/head-injury-sport.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/\",\"name\":\"Traumatismes cr\u00e2niens et cervicaux dans le sport - AMS Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/head-injury-sport.jpg\",\"datePublished\":\"2017-03-29T22:48:00+00:00\",\"dateModified\":\"2026-04-05T13:56:34+00:00\",\"description\":\"McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/head-injury-sport.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/head-injury-sport.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/traumatismes-craniens-et-cervicaux-dans-le-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traumatismes cr\u00e2niens et cervicaux dans le sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"name\":\"AMS Clinic\",\"description\":\"Montreal Rehabilitation and Physiotherapy Clinic\",\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\",\"name\":\"AMS Clinic\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"width\":280,\"height\":100,\"caption\":\"AMS Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\",\"name\":\"Rich &amp; Mo Physio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"caption\":\"Rich &amp; Mo Physio\"},\"description\":\"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/author\\\/rich-mo-physio-1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traumatismes cr\u00e2niens et cervicaux dans le sport - AMS Clinic","description":"McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/","og_locale":"fr_CA","og_type":"article","og_title":"Traumatismes cr\u00e2niens et cervicaux dans le sport - AMS Clinic","og_description":"McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport.","og_url":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/","og_site_name":"AMS Clinic","article_published_time":"2017-03-29T22:48:00+00:00","article_modified_time":"2026-04-05T13:56:34+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/03\/head-injury-sport.jpg","type":"image\/jpeg"}],"author":"Rich &amp; Mo Physio","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rich &amp; Mo Physio","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#article","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/"},"author":{"name":"Rich &amp; Mo Physio","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1"},"headline":"Traumatismes cr\u00e2niens et cervicaux dans le sport","datePublished":"2017-03-29T22:48:00+00:00","dateModified":"2026-04-05T13:56:34+00:00","mainEntityOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/03\/head-injury-sport.jpg","articleSection":["Blog"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/","url":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/","name":"Traumatismes cr\u00e2niens et cervicaux dans le sport - AMS Clinic","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#primaryimage"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/03\/head-injury-sport.jpg","datePublished":"2017-03-29T22:48:00+00:00","dateModified":"2026-04-05T13:56:34+00:00","description":"McIntosh et McCory ont r\u00e9alis\u00e9 en 2005 une revue de la litt\u00e9rature sur les blessures \u00e0 la t\u00eate et au cou dans le domaine de la m\u00e9decine du sport.","breadcrumb":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#primaryimage","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/03\/head-injury-sport.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/03\/head-injury-sport.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/amsclinic.ca\/fr\/blog\/traumatismes-craniens-et-cervicaux-dans-le-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amsclinic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Traumatismes cr\u00e2niens et cervicaux dans le sport"}]},{"@type":"WebSite","@id":"https:\/\/amsclinic.ca\/fr\/#website","url":"https:\/\/amsclinic.ca\/fr\/","name":"AMS Clinic","description":"Montreal Rehabilitation and Physiotherapy Clinic","publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amsclinic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/amsclinic.ca\/fr\/#organization","name":"AMS Clinic","url":"https:\/\/amsclinic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","width":280,"height":100,"caption":"AMS Clinic"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1","name":"Rich &amp; Mo Physio","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","caption":"Rich &amp; Mo Physio"},"description":"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.","url":"https:\/\/amsclinic.ca\/fr\/author\/rich-mo-physio-1\/"}]}},"authors":[{"term_id":80,"user_id":33,"is_guest":0,"slug":"rich-mo-physio-1","display_name":"Rich &amp; Mo Physio","avatar_url":{"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","url2x":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":""}],"_links":{"self":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/12183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/comments?post=12183"}],"version-history":[{"count":1,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/12183\/revisions"}],"predecessor-version":[{"id":19780,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/12183\/revisions\/19780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media\/6455"}],"wp:attachment":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media?parent=12183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/categories?post=12183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/tags?post=12183"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/ppma_author?post=12183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}