{"id":5242,"date":"2018-01-02T15:05:52","date_gmt":"2018-01-02T20:05:52","guid":{"rendered":"http:\/\/amsclinic.ca\/?p=5242"},"modified":"2026-04-05T09:51:21","modified_gmt":"2026-04-05T13:51:21","slug":"avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines","status":"publish","type":"post","link":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/","title":{"rendered":"Avez-vous peur de tomber? Pourquoi le risque de chute est-il plus pr\u00e9sent chez les a\u00een\u00e9s?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5240 alignright\" src=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs-217x300.jpg\" alt=\"\" width=\"217\" height=\"300\" srcset=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs-217x300.jpg 217w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg 250w\" sizes=\"(max-width: 217px) 100vw, 217px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2290 alignleft\" src=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2016\/01\/seniors-falling-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2016\/01\/seniors-falling-300x225.jpg 300w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2016\/01\/seniors-falling-768x576.jpg 768w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2016\/01\/seniors-falling-510x382.jpg 510w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2016\/01\/seniors-falling.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>La peur de tomber est un ph\u00e9nom\u00e8ne que l&rsquo;on rencontre \u00e0 tout \u00e2ge, qui arrive lorsqu&rsquo;on perd l&rsquo;\u00e9quilibre, un manque d&rsquo;attention, ou encore sur une surface instable&#8230; Plus on prend de l&rsquo;\u00e2ge\u00a0 et plus ce sentiment tend \u00e0 s&rsquo;intensifier, m\u00eame si cela reste un sujet tabou.<\/p>\n<p>Selon l&rsquo;article suivant, la majorit\u00e9 des cas de fracture de hanche sont dus \u00e0 des chutes associ\u00e9es un trouble d&rsquo;\u00e9quilibre. De nombreux facteurs peuvent affecter l&rsquo;\u00e9quilibre: la prise de m\u00e9dication, la mauvaise utilisation des verres correcteurs, ou encore la diminution du temps de r\u00e9action et ralentissement de l&rsquo;activation des r\u00e9flexes. L&rsquo;accompagnement par un professionnel peut vous \u00e9viter tout cela.<\/p>\n<p>En physioth\u00e9rapie, nous mesurant votre force, vos capacit\u00e9s fonctionnelles (monter les escaliers, la marche, et les arr\u00eats soudains), votre \u00e9quilibre, etc&#8230; . Nous \u00e9valuerons ainsi votre fonctionnalit\u00e9s et regarderons l&rsquo;impact de votre m\u00e9dication sur votre condition (ex: effet secondaire). Notre r\u00f4le ne s&rsquo;arr\u00eate pas seulement \u00e0 votre condition physique mais aussi \u00e0 votre environnement du quotidien (exemple : l&rsquo;am\u00e9nagement des pi\u00e8ces de la maison).\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1157 alignleft\" src=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-weight-ball-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-weight-ball-300x300.jpg 300w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-weight-ball-150x150.jpg 150w, https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/physio-weight-ball.jpg 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Osez parler de vos craintes, afin d&rsquo;avoir recours \u00e0 une approche personnalis\u00e9e. \u00c0 nos c\u00f4t\u00e9s, un support physique, mental, et moral sera\u00a0 \u00e0 votre port\u00e9e. Vous n&rsquo;aurez plus peur des chutes. Cette prise en charge, vous assurera une autonomie et un contr\u00f4le s\u00e9curitaire de votre corps\u00a0 favorable \u00e0 vos besoins.<\/p>\n<p><em>Source:\u00a0<\/em><a href=\"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/\">https:\/\/amsclinic.ca\/blog\/dramatically-lower-your-risk-and-fear-of-falling-with-physiotherapy\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La peur de tomber est un ph\u00e9nom\u00e8ne que l&rsquo;on rencontre \u00e0 tout \u00e2ge, qui arrive lorsqu&rsquo;on perd l&rsquo;\u00e9quilibre, un manque d&rsquo;attention, ou encore sur une surface instable&#8230; Plus on prend de l&rsquo;\u00e2ge\u00a0 et plus ce sentiment tend \u00e0 s&rsquo;intensifier, m\u00eame si cela reste un sujet tabou. Selon l&rsquo;article suivant, la majorit\u00e9 des cas de fracture [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":5240,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[12],"tags":[],"ppma_author":[80],"class_list":["post-5242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","author-rich-mo-physio-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pourquoi le risque de chute est-il plus pr\u00e9sent chez les ain\u00e9s?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi le risque de chute est-il plus pr\u00e9sent chez les ain\u00e9s?\" \/>\n<meta property=\"og:description\" content=\"La peur de tomber est un ph\u00e9nom\u00e8ne que l&rsquo;on rencontre \u00e0 tout \u00e2ge, qui arrive lorsqu&rsquo;on perd l&rsquo;\u00e9quilibre, un manque d&rsquo;attention, ou encore sur une surface instable&#8230; Plus on prend de l&rsquo;\u00e2ge\u00a0 et plus ce sentiment tend \u00e0 s&rsquo;intensifier, m\u00eame si cela reste un sujet tabou. Selon l&rsquo;article suivant, la majorit\u00e9 des cas de fracture [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/\" \/>\n<meta property=\"og:site_name\" content=\"AMS Clinic\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-02T20:05:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T13:51:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rich &amp; Mo Physio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rich &amp; Mo Physio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/\"},\"author\":{\"name\":\"Rich &amp; Mo Physio\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\"},\"headline\":\"Avez-vous peur de tomber? Pourquoi le risque de chute est-il plus pr\u00e9sent chez les a\u00een\u00e9s?\",\"datePublished\":\"2018-01-02T20:05:52+00:00\",\"dateModified\":\"2026-04-05T13:51:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/senior-falling-in-stairs.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/\",\"name\":\"Pourquoi le risque de chute est-il plus pr\u00e9sent chez les ain\u00e9s?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/senior-falling-in-stairs.jpg\",\"datePublished\":\"2018-01-02T20:05:52+00:00\",\"dateModified\":\"2026-04-05T13:51:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/senior-falling-in-stairs.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/senior-falling-in-stairs.jpg\",\"width\":250,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/blog\\\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avez-vous peur de tomber? Pourquoi le risque de chute est-il plus pr\u00e9sent chez les a\u00een\u00e9s?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"name\":\"AMS Clinic\",\"description\":\"Montreal Rehabilitation and Physiotherapy Clinic\",\"publisher\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#organization\",\"name\":\"AMS Clinic\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/ams-logo-Optimized280x100.png\",\"width\":280,\"height\":100,\"caption\":\"AMS Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/c21c16a003fbe73085e73bf5c80adcc1\",\"name\":\"Rich &amp; Mo Physio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"contentUrl\":\"https:\\\/\\\/amsclinic.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/unnamed-2026-03-30T191932.757-1.jpg\",\"caption\":\"Rich &amp; Mo Physio\"},\"description\":\"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.\",\"url\":\"https:\\\/\\\/amsclinic.ca\\\/fr\\\/author\\\/rich-mo-physio-1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pourquoi le risque de chute est-il plus pr\u00e9sent chez les ain\u00e9s?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/","og_locale":"fr_CA","og_type":"article","og_title":"Pourquoi le risque de chute est-il plus pr\u00e9sent chez les ain\u00e9s?","og_description":"La peur de tomber est un ph\u00e9nom\u00e8ne que l&rsquo;on rencontre \u00e0 tout \u00e2ge, qui arrive lorsqu&rsquo;on perd l&rsquo;\u00e9quilibre, un manque d&rsquo;attention, ou encore sur une surface instable&#8230; Plus on prend de l&rsquo;\u00e2ge\u00a0 et plus ce sentiment tend \u00e0 s&rsquo;intensifier, m\u00eame si cela reste un sujet tabou. Selon l&rsquo;article suivant, la majorit\u00e9 des cas de fracture [&hellip;]","og_url":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/","og_site_name":"AMS Clinic","article_published_time":"2018-01-02T20:05:52+00:00","article_modified_time":"2026-04-05T13:51:21+00:00","og_image":[{"width":250,"height":345,"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg","type":"image\/jpeg"}],"author":"Rich &amp; Mo Physio","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rich &amp; Mo Physio","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#article","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/"},"author":{"name":"Rich &amp; Mo Physio","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1"},"headline":"Avez-vous peur de tomber? Pourquoi le risque de chute est-il plus pr\u00e9sent chez les a\u00een\u00e9s?","datePublished":"2018-01-02T20:05:52+00:00","dateModified":"2026-04-05T13:51:21+00:00","mainEntityOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg","articleSection":["Blog"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/","url":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/","name":"Pourquoi le risque de chute est-il plus pr\u00e9sent chez les ain\u00e9s?","isPartOf":{"@id":"https:\/\/amsclinic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#primaryimage"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#primaryimage"},"thumbnailUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg","datePublished":"2018-01-02T20:05:52+00:00","dateModified":"2026-04-05T13:51:21+00:00","breadcrumb":{"@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#primaryimage","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2018\/01\/senior-falling-in-stairs.jpg","width":250,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/amsclinic.ca\/fr\/blog\/avez-vous-peur-de-tomber-pourquoi-le-risque-de-chute-est-il-plus-present-chez-les-aines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amsclinic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Avez-vous peur de tomber? Pourquoi le risque de chute est-il plus pr\u00e9sent chez les a\u00een\u00e9s?"}]},{"@type":"WebSite","@id":"https:\/\/amsclinic.ca\/fr\/#website","url":"https:\/\/amsclinic.ca\/fr\/","name":"AMS Clinic","description":"Montreal Rehabilitation and Physiotherapy Clinic","publisher":{"@id":"https:\/\/amsclinic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amsclinic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/amsclinic.ca\/fr\/#organization","name":"AMS Clinic","url":"https:\/\/amsclinic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2017\/02\/ams-logo-Optimized280x100.png","width":280,"height":100,"caption":"AMS Clinic"},"image":{"@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/amsclinic.ca\/fr\/#\/schema\/person\/c21c16a003fbe73085e73bf5c80adcc1","name":"Rich &amp; Mo Physio","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg159c645a471dce2caa494b2bda7ec816","url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","contentUrl":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","caption":"Rich &amp; Mo Physio"},"description":"Nous sommes des physioth\u00e9rapeutes passionn\u00e9s par le mouvement et la r\u00e9adaptation, avec un objectif clair : aider les gens \u00e0 mieux comprendre leur douleur et \u00e0 retrouver une vie active, sans limitation. \u00c0 travers notre pratique et nos contenus, nous partageons des approches concr\u00e8tes, fond\u00e9es sur la science, pour pr\u00e9venir les blessures, soulager les douleurs et am\u00e9liorer durablement la mobilit\u00e9. Nous croyons qu\u2019un patient bien inform\u00e9 prend de meilleures d\u00e9cisions et obtient de meilleurs r\u00e9sultats. Richard Bouzaglou, B.Sc. PT Physioth\u00e9rapeute | Cofondateur Professionnel exp\u00e9riment\u00e9, Richard est cofondateur du Centre M\u00e9dical et de R\u00e9adaptation AMS, o\u00f9 il joue un r\u00f4le cl\u00e9 depuis 2008. Fort d\u2019une formation en m\u00e9decine du sport et en physioth\u00e9rapie, il a d\u00e9velopp\u00e9 une solide expertise, notamment aupr\u00e8s d\u2019athl\u00e8tes d\u2019\u00e9lite. Sa pratique repose sur une approche globale, int\u00e9grant th\u00e9rapie manuelle avanc\u00e9e, r\u00e9adaptation fonctionnelle et prise en charge personnalis\u00e9e. Engag\u00e9 dans la formation continue et l\u2019encadrement d\u2019\u00e9tudiants, il se distingue par sa rigueur clinique et sa capacit\u00e9 \u00e0 \u00e9tablir une relation de confiance durable avec ses patients. Moshe Vazana Physioth\u00e9rapeute Avec plus de 15 ans d\u2019exp\u00e9rience, Moshe est reconnu pour son approche pr\u00e9cise, fond\u00e9e sur des donn\u00e9es probantes. Dipl\u00f4m\u00e9 en physioth\u00e9rapie et form\u00e9 \u00e0 plusieurs m\u00e9thodes avanc\u00e9es, dont la M\u00e9thode McKenzie (MDT) et le concept Mulligan, il se sp\u00e9cialise dans le traitement des troubles musculo-squelettiques et de la colonne vert\u00e9brale. Son parcours international et son engagement envers l\u2019excellence lui permettent d\u2019offrir des soins adapt\u00e9s, efficaces et durables. Passionn\u00e9 par la transmission du savoir, il participe \u00e9galement \u00e0 la formation de futurs professionnels en physioth\u00e9rapie.","url":"https:\/\/amsclinic.ca\/fr\/author\/rich-mo-physio-1\/"}]}},"authors":[{"term_id":80,"user_id":33,"is_guest":0,"slug":"rich-mo-physio-1","display_name":"Rich &amp; Mo Physio","avatar_url":{"url":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg","url2x":"https:\/\/amsclinic.ca\/wp-content\/uploads\/2026\/03\/unnamed-2026-03-30T191932.757-1.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":""}],"_links":{"self":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/5242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/comments?post=5242"}],"version-history":[{"count":1,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/5242\/revisions"}],"predecessor-version":[{"id":19760,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/posts\/5242\/revisions\/19760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media\/5240"}],"wp:attachment":[{"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/media?parent=5242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/categories?post=5242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/tags?post=5242"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/amsclinic.ca\/fr\/wp-json\/wp\/v2\/ppma_author?post=5242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}